{"id":5387,"date":"2022-06-02T02:33:23","date_gmt":"2022-06-02T02:33:23","guid":{"rendered":"https:\/\/live-amsted-industries.pantheonsite.io\/unidade-de-negocios\/conmet\/"},"modified":"2022-09-14T19:55:42","modified_gmt":"2022-09-14T19:55:42","slug":"conmet","status":"publish","type":"page","link":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/","title":{"rendered":"ConMet"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5387\" class=\"elementor elementor-5387 elementor-198\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a306989 elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"5a306989\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c0e42cb\" data-id=\"5c0e42cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5135dc6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5135dc6c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-307805e4\" data-id=\"307805e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63fe38c0 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"63fe38c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ConMet<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19dde460 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"19dde460\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tecnologias transformadoras para a ind\u00fastria global de ve\u00edculos comerciais<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-43920607\" data-id=\"43920607\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1af2320d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1af2320d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5a5ebd65\" data-id=\"5a5ebd65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13f775ab elementor-widget elementor-widget-image\" data-id=\"13f775ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"362\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/conmet-logo.png\" class=\"attachment-large size-large wp-image-3495\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/conmet-logo.png 800w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/conmet-logo-300x136.png 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/conmet-logo-768x348.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7b9085fd\" data-id=\"7b9085fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36fcc3a3 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"36fcc3a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.conmet.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visite o site<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-13437a1d\" data-id=\"13437a1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34b4b30 elementor-widget elementor-widget-heading\" data-id=\"34b4b30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mais de 5.100 <span style=\"font-family:Quicksand;font-size:1rem\">funcion\u00e1rios<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5c42152e\" data-id=\"5c42152e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1281d82b elementor-widget elementor-widget-heading\" data-id=\"1281d82b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Est. 1964 1964  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-40b067e9\" data-id=\"40b067e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e6af62f elementor-widget elementor-widget-heading\" data-id=\"2e6af62f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">16 <span style=\"font-family:Quicksand;font-size:1rem\">pa\u00edses<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a06ec24 elementor-section-full_width elementor-section-height-min-height section-img-right elementor-section-height-default elementor-section-items-middle\" data-id=\"a06ec24\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ee23dd\" data-id=\"9ee23dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4dd43bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4dd43bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-615e62f2\" data-id=\"615e62f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42b0ad8d elementor-widget elementor-widget-text-editor\" data-id=\"42b0ad8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fundada em 1964, a ConMet \u00e9 uma fabricante l\u00edder global de conjuntos de cubos de roda, pl\u00e1sticos estruturais e componentes de fundi\u00e7\u00e3o de alum\u00ednio para a ind\u00fastria de ve\u00edculos comerciais. Hoje, os produtos ConMet s\u00e3o equipamentos padr\u00e3o na maioria dos ve\u00edc ulos pesados na Am\u00e9rica do Norte e t\u00eam uma presen\u00e7a crescente em todo o mundo. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2683d612\" data-id=\"2683d612\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-172d8e31 elementor-widget elementor-widget-image\" data-id=\"172d8e31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"498\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-1024x637.jpg\" class=\"attachment-large size-large wp-image-2148\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-1024x637.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-300x187.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-768x478.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-1536x956.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b78bc0f elementor-section-full_width elementor-section-height-min-height section-img-left elementor-section-height-default elementor-section-items-middle\" data-id=\"5b78bc0f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2acd9c6c\" data-id=\"2acd9c6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-316d769c elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"316d769c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4962d99b\" data-id=\"4962d99b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-136325af elementor-widget elementor-widget-image\" data-id=\"136325af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-1024x696.jpg\" class=\"attachment-large size-large wp-image-2102\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-1024x696.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-300x204.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-768x522.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-1536x1044.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a82d0e8\" data-id=\"a82d0e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e35e52a elementor-widget elementor-widget-heading\" data-id=\"7e35e52a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produtos OEM de primeira linha<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-551ceffa elementor-widget elementor-widget-text-editor\" data-id=\"551ceffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A ConMet trabalha com os principais fabricantes de equipamentos originais h\u00e1 mais de 50 anos, fornecendo experi\u00eancia em design, engenharia e tes tes para desenvolver produtos e inova\u00e7\u00f5es premium para a ind\u00fastria de ve\u00edculos comerciais. Os conjuntos de cubos de roda ConMet, como os patenteados PreSet\u00ae e PreSet Plus\u00ae, s\u00e3o habilmente projetados para ajudar a reduzir os custos de manuten\u00e7\u00e3o e prolongar a vida \u00fatil geral do ve\u00edculo. Os tambores de freio TruTurn\u00ae totalmente usinados criam os conjuntos de rotor e freio mais avan\u00e7ados do mercado.  <\/p>\n<p>Al\u00e9m disso, a ConMet oferece experi\u00eancia em design e engenharia l\u00edder do setor para componentes de pl\u00e1stico e al um\u00ednio propriet\u00e1rios de OEM. Dos esbo\u00e7os conceituais \u00e0 fabrica\u00e7\u00e3o final, a ConMet \u00e9 especializada em solu\u00e7\u00f5es leves e de baixa press\u00e3o testadas com os mais altos padr\u00f5es. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46736301 elementor-section-full_width elementor-section-height-min-height section-img-right elementor-section-height-default elementor-section-items-middle\" data-id=\"46736301\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33a01866\" data-id=\"33a01866\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5240c6a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5240c6a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79fde285\" data-id=\"79fde285\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e68b4d2 elementor-widget elementor-widget-heading\" data-id=\"6e68b4d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sistemas e componentes originais OEM para o mercado de reposi\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fde0b1e elementor-widget elementor-widget-text-editor\" data-id=\"1fde0b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quando se trata de desempenho de ponta de roda, a ConMet se dedica a fornecer o melhor custo &#8211; benef\u00edcio por milha e as op\u00e7\u00f5es de produtos mais seguras para clientes da ind\u00fastria de ve\u00edculos comerciais. \u00c9 por isso que a ind\u00fastria de ve\u00edculos comerciais recorre \u00e0 ConMet para ki ts de servi\u00e7o, sistemas e componentes que servem como substitutos diretos para equipamentos instalados originalmente. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52c77c54\" data-id=\"52c77c54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48f32a6c elementor-widget elementor-widget-image\" data-id=\"48f32a6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-1024x696.jpg\" class=\"attachment-large size-large wp-image-2109\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-1024x696.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-300x204.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-768x522.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-1536x1044.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7021d7a2 elementor-section-full_width elementor-section-height-min-height section-img-left elementor-section-height-default elementor-section-items-middle\" data-id=\"7021d7a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-667b93cd\" data-id=\"667b93cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-685832ad elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"685832ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-687c8720\" data-id=\"687c8720\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73cf95af elementor-widget elementor-widget-image\" data-id=\"73cf95af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-1024x696.jpg\" class=\"attachment-large size-large wp-image-2100\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-1024x696.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-300x204.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-768x522.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-1536x1044.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61f2bbe6\" data-id=\"61f2bbe6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0995704 elementor-widget elementor-widget-image\" data-id=\"0995704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"477\" height=\"237\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-digital-logo.png\" class=\"attachment-large size-large wp-image-2116\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-digital-logo.png 477w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-digital-logo-300x149.png 300w\" sizes=\"(max-width: 477px) 100vw, 477px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46bdc636 elementor-widget elementor-widget-heading\" data-id=\"46bdc636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fornecendo intelig\u00eancia acion\u00e1vel para melhorar o gerenciamento de frota<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd8d97f elementor-widget elementor-widget-text-editor\" data-id=\"bd8d97f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A ConMet Digital foi criada em 2019 para promover a inova\u00e7\u00e3o de IoT da ConMet para ve\u00edculos pesados. Juntamente com a experi\u00eancia inigual\u00e1vel em ve\u00edculos comerciais e o suporte da ConMet, a ConMet Digital fornece insights hol\u00edsticos e acion\u00e1veis sobre o ecossistema de trator &#8211; reboque para ajudar as frotas a melhorar o t empo de atividade, seguran\u00e7a, manuten\u00e7\u00e3o e efici\u00eancia operacional geral. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b003dd0 elementor-section-full_width elementor-section-height-min-height section-img-right elementor-section-height-default elementor-section-items-middle\" data-id=\"1b003dd0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fb7f410\" data-id=\"4fb7f410\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b6566b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b6566b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-129922f7\" data-id=\"129922f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-318324c elementor-widget elementor-widget-image\" data-id=\"318324c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"601\" height=\"266\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/emobility-logo.png\" class=\"attachment-large size-large wp-image-2117\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/emobility-logo.png 601w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/emobility-logo-300x133.png 300w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e2a6ae0 elementor-widget elementor-widget-heading\" data-id=\"6e2a6ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solu\u00e7\u00f5es avan\u00e7adas de eletrifica\u00e7\u00e3o para ve\u00edculos comerciais<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-312f4bc2 elementor-widget elementor-widget-text-editor\" data-id=\"312f4bc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Com uma heran\u00e7a de 50 anos de design inovador, engenharia e fabrica\u00e7\u00e3o, a ConMet criou a ConMet eMobility, uma nova unidade de neg\u00f3cios dedicada a fornecer tecnologias transformadoras para a era da energia alternativa. A ConMet eMobility permite o desenvol vimento de ve\u00edculos comerciais com emiss\u00f5es zero, ajudando as frotas a superar as metas de responsabilidade social corporativa ao atingir o equil\u00edbrio certo entre melhor economia de combust\u00edvel, redu\u00e7\u00e3o de emiss\u00f5es e produtividade. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a1ff30\" data-id=\"3a1ff30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-544189bd elementor-widget elementor-widget-image\" data-id=\"544189bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-1024x696.jpg\" class=\"attachment-large size-large wp-image-2099\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-1024x696.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-300x204.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-768x522.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-1536x1044.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b4cb764 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b4cb764\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a060ee9\" data-id=\"4a060ee9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61c35c63 elementor-widget elementor-widget-shortcode\" data-id=\"61c35c63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ConMet Tecnologias transformadoras para a ind\u00fastria global de ve\u00edculos comerciais Visite o site Mais de 5.100 funcion\u00e1rios Est. 1964 1964 16 pa\u00edses Fundada em 1964, a ConMet \u00e9 uma fabricante l\u00edder global de conjuntos de cubos de roda, pl\u00e1sticos estruturais e componentes de fundi\u00e7\u00e3o de alum\u00ednio para a ind\u00fastria de ve\u00edculos comerciais. Hoje, os produtos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":5373,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"search-category":[17],"class_list":["post-5387","page","type-page","status-publish","hentry","search-category-business-units"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ConMet - Amsted Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ConMet - Amsted Industries\" \/>\n<meta property=\"og:description\" content=\"ConMet Tecnologias transformadoras para a ind\u00fastria global de ve\u00edculos comerciais Visite o site Mais de 5.100 funcion\u00e1rios Est. 1964 1964 16 pa\u00edses Fundada em 1964, a ConMet \u00e9 uma fabricante l\u00edder global de conjuntos de cubos de roda, pl\u00e1sticos estruturais e componentes de fundi\u00e7\u00e3o de alum\u00ednio para a ind\u00fastria de ve\u00edculos comerciais. Hoje, os produtos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/\" \/>\n<meta property=\"og:site_name\" content=\"Amsted Industries\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-14T19:55:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/conmet\\\/\",\"url\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/conmet\\\/\",\"name\":\"ConMet - Amsted Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/conmet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/conmet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/live-amsted-industries.pantheonsite.io\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/conmet-logo.png\",\"datePublished\":\"2022-06-02T02:33:23+00:00\",\"dateModified\":\"2022-09-14T19:55:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/conmet\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/conmet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/conmet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/live-amsted-industries.pantheonsite.io\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/conmet-logo.png\",\"contentUrl\":\"https:\\\/\\\/live-amsted-industries.pantheonsite.io\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/conmet-logo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/conmet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unidade de Neg\u00f3cios\",\"item\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/unidade-de-negocios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ConMet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/\",\"name\":\"Amsted Industries\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amsted.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ConMet - Amsted Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/","og_locale":"pt_BR","og_type":"article","og_title":"ConMet - Amsted Industries","og_description":"ConMet Tecnologias transformadoras para a ind\u00fastria global de ve\u00edculos comerciais Visite o site Mais de 5.100 funcion\u00e1rios Est. 1964 1964 16 pa\u00edses Fundada em 1964, a ConMet \u00e9 uma fabricante l\u00edder global de conjuntos de cubos de roda, pl\u00e1sticos estruturais e componentes de fundi\u00e7\u00e3o de alum\u00ednio para a ind\u00fastria de ve\u00edculos comerciais. Hoje, os produtos [&hellip;]","og_url":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/","og_site_name":"Amsted Industries","article_modified_time":"2022-09-14T19:55:42+00:00","og_image":[{"url":"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/","url":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/","name":"ConMet - Amsted Industries","isPartOf":{"@id":"https:\/\/www.amsted.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/#primaryimage"},"image":{"@id":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/#primaryimage"},"thumbnailUrl":"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png","datePublished":"2022-06-02T02:33:23+00:00","dateModified":"2022-09-14T19:55:42+00:00","breadcrumb":{"@id":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/#primaryimage","url":"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png","contentUrl":"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/conmet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.amsted.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Unidade de Neg\u00f3cios","item":"https:\/\/www.amsted.com\/pt-br\/unidade-de-negocios\/"},{"@type":"ListItem","position":3,"name":"ConMet"}]},{"@type":"WebSite","@id":"https:\/\/www.amsted.com\/pt-br\/#website","url":"https:\/\/www.amsted.com\/pt-br\/","name":"Amsted Industries","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amsted.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/pages\/5387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/comments?post=5387"}],"version-history":[{"count":3,"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/pages\/5387\/revisions"}],"predecessor-version":[{"id":5390,"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/pages\/5387\/revisions\/5390"}],"up":[{"embeddable":true,"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/pages\/5373"}],"wp:attachment":[{"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/media?parent=5387"}],"wp:term":[{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/www.amsted.com\/pt-br\/wp-json\/wp\/v2\/search-category?post=5387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}