{"id":5252,"date":"2022-06-02T02:33:23","date_gmt":"2022-06-02T02:33:23","guid":{"rendered":"https:\/\/live-amsted-industries.pantheonsite.io\/unidades-de-negocio\/conmet\/"},"modified":"2022-09-15T18:54:58","modified_gmt":"2022-09-15T18:54:58","slug":"conmet","status":"publish","type":"page","link":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/","title":{"rendered":"ConMet"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5252\" class=\"elementor elementor-5252 elementor-198\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a306989 elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"5a306989\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c0e42cb\" data-id=\"5c0e42cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5135dc6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5135dc6c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-307805e4\" data-id=\"307805e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63fe38c0 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"63fe38c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ConMet<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19dde460 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"19dde460\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tecnolog\u00edas transformativas para la industria global de veh\u00edculos comerciales<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-43920607\" data-id=\"43920607\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1af2320d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1af2320d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5a5ebd65\" data-id=\"5a5ebd65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13f775ab elementor-widget elementor-widget-image\" data-id=\"13f775ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"362\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/conmet-logo.png\" class=\"attachment-large size-large wp-image-3495\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/conmet-logo.png 800w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/conmet-logo-300x136.png 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/conmet-logo-768x348.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7b9085fd\" data-id=\"7b9085fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36fcc3a3 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"36fcc3a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.conmet.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visitar sitio web<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-13437a1d\" data-id=\"13437a1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34b4b30 elementor-widget elementor-widget-heading\" data-id=\"34b4b30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5,100 + <span style=\"font-family:Quicksand;font-size:1rem\">empleados<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5c42152e\" data-id=\"5c42152e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1281d82b elementor-widget elementor-widget-heading\" data-id=\"1281d82b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Desde 1964  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-40b067e9\" data-id=\"40b067e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e6af62f elementor-widget elementor-widget-heading\" data-id=\"2e6af62f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">16 <span style=\"font-family:Quicksand;font-size:1rem\">pa\u00edses<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a06ec24 elementor-section-full_width elementor-section-height-min-height section-img-right elementor-section-height-default elementor-section-items-middle\" data-id=\"a06ec24\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ee23dd\" data-id=\"9ee23dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4dd43bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4dd43bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-615e62f2\" data-id=\"615e62f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42b0ad8d elementor-widget elementor-widget-text-editor\" data-id=\"42b0ad8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fundado en 1964, ConMet es un fabricante global l\u00edder de conjuntos de cubo de rueda, pl\u00e1sticos estructurales y componentes de fundici\u00f3n de aluminio para la industria de veh\u00edculos comerciales. Hoy en d\u00eda, los productos ConMet son equipos est\u00e1ndar en la mayor\u00eda de los veh\u00edculos pesados en Am\u00e9rica del Norte y tienen una huella creciente en todo el mundo. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2683d612\" data-id=\"2683d612\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-172d8e31 elementor-widget elementor-widget-image\" data-id=\"172d8e31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"498\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-1024x637.jpg\" class=\"attachment-large size-large wp-image-2148\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-1024x637.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-300x187.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-768x478.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck-1536x956.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-intro-truck.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b78bc0f elementor-section-full_width elementor-section-height-min-height section-img-left elementor-section-height-default elementor-section-items-middle\" data-id=\"5b78bc0f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2acd9c6c\" data-id=\"2acd9c6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-316d769c elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"316d769c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4962d99b\" data-id=\"4962d99b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-136325af elementor-widget elementor-widget-image\" data-id=\"136325af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-1024x696.jpg\" class=\"attachment-large size-large wp-image-2102\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-1024x696.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-300x204.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-768x522.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut-1536x1044.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-presetplut.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a82d0e8\" data-id=\"a82d0e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e35e52a elementor-widget elementor-widget-heading\" data-id=\"7e35e52a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Productos de primer ajuste por fabricantes de equipos originales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-551ceffa elementor-widget elementor-widget-text-editor\" data-id=\"551ceffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ConMet ha estado trabajando con fabricantes l\u00edderes de equipos originales durante m\u00e1s de 50 a\u00f1os, proporcionando experiencia en dise\u00f1o, ingenier\u00eda y pruebas para desarrollar productos e innovaciones premium para la industria de veh\u00edculos comerciales. Los conjuntos de cubo de rueda ConMet, como los patentados PreSet\u00ae y PreSet Plus\u00ae, est\u00e1n dise\u00f1ados de forma experta para ayudar a reducir los costos de mantenimiento y extender la vida \u00fatil general del veh\u00edculo. Los tambores de freno TruTurn\u00ae completamente mecanizados crean los conjuntos de frenos y rotores m\u00e1s avanzados del mercado.  <\/p>\n<p>Adem\u00e1s, ConMet proporciona experiencia en dise\u00f1o e ingenier\u00eda l\u00edder en la industria para componentes de pl\u00e1stico y aluminio patentados por fabricantes de equipos originales. Desde bocetos conceptuales hasta la fabricaci\u00f3n final, ConMet se especializa en soluciones ligeras y de baja presi\u00f3n probadas con los m\u00e1s altos est\u00e1ndares. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46736301 elementor-section-full_width elementor-section-height-min-height section-img-right elementor-section-height-default elementor-section-items-middle\" data-id=\"46736301\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33a01866\" data-id=\"33a01866\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5240c6a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5240c6a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79fde285\" data-id=\"79fde285\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e68b4d2 elementor-widget elementor-widget-heading\" data-id=\"6e68b4d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Componentes y sistemas originales de fabricantes de equipos originales para el mercado de accesorios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fde0b1e elementor-widget elementor-widget-text-editor\" data-id=\"1fde0b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando se trata del rendimiento de terminales de ruedas, ConMet se dedica a proporcionar la mejor relaci\u00f3n calidad-precio por milla y las opciones de productos m\u00e1s seguras para los clientes de la industria de veh\u00edculos comerciales. Es por eso que la industria de veh\u00edculos comerciales recurre a ConMet para obtener kits de servicio, sistemas y componentes que sirven como reemplazos directos de los equipos instalados originalmente. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52c77c54\" data-id=\"52c77c54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48f32a6c elementor-widget elementor-widget-image\" data-id=\"48f32a6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-1024x696.jpg\" class=\"attachment-large size-large wp-image-2109\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-1024x696.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-300x204.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-768x522.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu-1536x1044.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-aftermarket-bu.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7021d7a2 elementor-section-full_width elementor-section-height-min-height section-img-left elementor-section-height-default elementor-section-items-middle\" data-id=\"7021d7a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-667b93cd\" data-id=\"667b93cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-685832ad elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"685832ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-687c8720\" data-id=\"687c8720\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73cf95af elementor-widget elementor-widget-image\" data-id=\"73cf95af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-1024x696.jpg\" class=\"attachment-large size-large wp-image-2100\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-1024x696.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-300x204.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-768x522.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital-1536x1044.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-digital.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61f2bbe6\" data-id=\"61f2bbe6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0995704 elementor-widget elementor-widget-image\" data-id=\"0995704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"477\" height=\"237\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-digital-logo.png\" class=\"attachment-large size-large wp-image-2116\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-digital-logo.png 477w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-digital-logo-300x149.png 300w\" sizes=\"(max-width: 477px) 100vw, 477px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46bdc636 elementor-widget elementor-widget-heading\" data-id=\"46bdc636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Proporcionar inteligencia procesable para mejorar la gesti\u00f3n de la flota<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd8d97f elementor-widget elementor-widget-text-editor\" data-id=\"bd8d97f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ConMet Digital se estableci\u00f3 en 2019 para avanzar en la innovaci\u00f3n del Internet de las Cosas (IoT, por sus siglas en ingl\u00e9s) de ConMet para veh\u00edculos pesados. Junto con la incomparable experiencia en veh\u00edculos comerciales y el soporte de ConMet, ConMet Digital proporciona informaci\u00f3n integral y pr\u00e1ctica sobre el ecosistema tractor-remolque para ayudar a las flotas a mejorar el tiempo de actividad, la seguridad, el mantenimiento y la eficiencia operativa general. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b003dd0 elementor-section-full_width elementor-section-height-min-height section-img-right elementor-section-height-default elementor-section-items-middle\" data-id=\"1b003dd0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fb7f410\" data-id=\"4fb7f410\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b6566b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b6566b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-129922f7\" data-id=\"129922f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-318324c elementor-widget elementor-widget-image\" data-id=\"318324c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"601\" height=\"266\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/emobility-logo.png\" class=\"attachment-large size-large wp-image-2117\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/emobility-logo.png 601w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/emobility-logo-300x133.png 300w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e2a6ae0 elementor-widget elementor-widget-heading\" data-id=\"6e2a6ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Soluciones avanzadas de electrificaci\u00f3n para veh\u00edculos comerciales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-312f4bc2 elementor-widget elementor-widget-text-editor\" data-id=\"312f4bc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con un legado de 50 a\u00f1os de dise\u00f1o innovador, ingenier\u00eda y fabricaci\u00f3n, ConMet ha formado ConMet eMobility, una nueva unidad de negocio dedicada a proporcionar tecnolog\u00edas transformadoras para una era de energ\u00eda alternativa. ConMet eMobility est\u00e1 permitiendo el desarrollo de veh\u00edculos comerciales sin emisiones, ayudando a las flotas a superar los objetivos de Responsabilidad Social Corporativa, al tiempo que logra el equilibrio adecuado entre la mejora del ahorro de combustible, la reducci\u00f3n de emisiones y el rendimiento <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3a1ff30\" data-id=\"3a1ff30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-544189bd elementor-widget elementor-widget-image\" data-id=\"544189bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-1024x696.jpg\" class=\"attachment-large size-large wp-image-2099\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-1024x696.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-300x204.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-768x522.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility-1536x1044.jpg 1536w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/06\/conmet-bu-emobility.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b4cb764 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b4cb764\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a060ee9\" data-id=\"4a060ee9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61c35c63 elementor-widget elementor-widget-shortcode\" data-id=\"61c35c63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ConMet Tecnolog\u00edas transformativas para la industria global de veh\u00edculos comerciales Visitar sitio web 5,100 + empleados Desde 1964 16 pa\u00edses Fundado en 1964, ConMet es un fabricante global l\u00edder de conjuntos de cubo de rueda, pl\u00e1sticos estructurales y componentes de fundici\u00f3n de aluminio para la industria de veh\u00edculos comerciales. Hoy en d\u00eda, los productos ConMet [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":5240,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"search-category":[17],"class_list":["post-5252","page","type-page","status-publish","hentry","search-category-business-units"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ConMet - Amsted Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ConMet - Amsted Industries\" \/>\n<meta property=\"og:description\" content=\"ConMet Tecnolog\u00edas transformativas para la industria global de veh\u00edculos comerciales Visitar sitio web 5,100 + empleados Desde 1964 16 pa\u00edses Fundado en 1964, ConMet es un fabricante global l\u00edder de conjuntos de cubo de rueda, pl\u00e1sticos estructurales y componentes de fundici\u00f3n de aluminio para la industria de veh\u00edculos comerciales. Hoy en d\u00eda, los productos ConMet [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/\" \/>\n<meta property=\"og:site_name\" content=\"Amsted Industries\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-15T18:54:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/conmet\\\/\",\"url\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/conmet\\\/\",\"name\":\"ConMet - Amsted Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/conmet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/conmet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/live-amsted-industries.pantheonsite.io\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/conmet-logo.png\",\"datePublished\":\"2022-06-02T02:33:23+00:00\",\"dateModified\":\"2022-09-15T18:54:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/conmet\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/conmet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/conmet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/live-amsted-industries.pantheonsite.io\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/conmet-logo.png\",\"contentUrl\":\"https:\\\/\\\/live-amsted-industries.pantheonsite.io\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/conmet-logo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/conmet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unidades de negocio\",\"item\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/unidades-de-negocio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ConMet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/\",\"name\":\"Amsted Industries\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ConMet - Amsted Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/","og_locale":"es_ES","og_type":"article","og_title":"ConMet - Amsted Industries","og_description":"ConMet Tecnolog\u00edas transformativas para la industria global de veh\u00edculos comerciales Visitar sitio web 5,100 + empleados Desde 1964 16 pa\u00edses Fundado en 1964, ConMet es un fabricante global l\u00edder de conjuntos de cubo de rueda, pl\u00e1sticos estructurales y componentes de fundici\u00f3n de aluminio para la industria de veh\u00edculos comerciales. Hoy en d\u00eda, los productos ConMet [&hellip;]","og_url":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/","og_site_name":"Amsted Industries","article_modified_time":"2022-09-15T18:54:58+00:00","og_image":[{"url":"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/","url":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/","name":"ConMet - Amsted Industries","isPartOf":{"@id":"https:\/\/www.amsted.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/#primaryimage"},"image":{"@id":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/#primaryimage"},"thumbnailUrl":"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png","datePublished":"2022-06-02T02:33:23+00:00","dateModified":"2022-09-15T18:54:58+00:00","breadcrumb":{"@id":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/#primaryimage","url":"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png","contentUrl":"https:\/\/live-amsted-industries.pantheonsite.io\/wp-content\/uploads\/2022\/08\/conmet-logo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/conmet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.amsted.com\/es\/homepage\/"},{"@type":"ListItem","position":2,"name":"Unidades de negocio","item":"https:\/\/www.amsted.com\/es\/unidades-de-negocio\/"},{"@type":"ListItem","position":3,"name":"ConMet"}]},{"@type":"WebSite","@id":"https:\/\/www.amsted.com\/es\/#website","url":"https:\/\/www.amsted.com\/es\/","name":"Amsted Industries","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amsted.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/pages\/5252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/comments?post=5252"}],"version-history":[{"count":3,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/pages\/5252\/revisions"}],"predecessor-version":[{"id":5625,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/pages\/5252\/revisions\/5625"}],"up":[{"embeddable":true,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/pages\/5240"}],"wp:attachment":[{"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/media?parent=5252"}],"wp:term":[{"taxonomy":"search-category","embeddable":true,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/search-category?post=5252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}