{"id":6599,"date":"2022-08-12T03:54:17","date_gmt":"2022-08-12T03:54:17","guid":{"rendered":"https:\/\/live-amsted-industries.pantheonsite.io\/profiles\/sarah-evans\/"},"modified":"2022-09-22T14:18:35","modified_gmt":"2022-09-22T14:18:35","slug":"sarah-evans","status":"publish","type":"career_profiles","link":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/","title":{"rendered":"Sarah Evans"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6599\" class=\"elementor elementor-6599\" data-elementor-post-type=\"career_profiles\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3451685f elementor-section-height-min-height elementor-section-full_width elementor-section-content-bottom elementor-section-items-bottom elementor-section-height-default\" data-id=\"3451685f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d0ae442\" data-id=\"5d0ae442\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1565cf7e elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1565cf7e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c32f58c\" data-id=\"5c32f58c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bab3f4 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bab3f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sarah Evans<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27510705 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"27510705\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>ConMet<\/strong><br \/>Gerente de Comercializaci\u00f3n de Producto<br \/>Vancouver, Washington, Estados Unidos<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-76238ac2\" data-id=\"76238ac2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2eda35dd elementor-section-full_width section-img-right elementor-section-height-default elementor-section-height-default\" data-id=\"2eda35dd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7103ac26\" data-id=\"7103ac26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-79e8c446 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79e8c446\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31ce98a6\" data-id=\"31ce98a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74c477ef elementor-widget elementor-widget-heading\" data-id=\"74c477ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Talento para mantener la comunicaci\u00f3n con el cliente usando tecnolog\u00eda de punta<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac5e390 elementor-widget elementor-widget-text-editor\" data-id=\"2ac5e390\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sarah pas\u00f3 de la comercializaci\u00f3n de equipos m\u00e9dicos a la industria de transporte comercial porque estaba fascinada por la velocidad en que los productos y servicios para veh\u00edculos adoptaban nuevas tecnolog\u00edas. Sab\u00eda que iba a encontrar una historia irresistible y la posibilidad de crecer r\u00e1pidamente en su carrera. En 5 a\u00f1os desde que se uni\u00f3 a ConMet, ha progresado desde ser Especialista en Comercializaci\u00f3n de un equipo en ciernes que reci\u00e9n estaba comenzando a desarrollar comunicaci\u00f3n de producto estrat\u00e9gica.<\/p>\n<p>Impulsada por su propia visi\u00f3n y motivada por la direcci\u00f3n ejecutiva de ConMet, Sarah elabor\u00f3 una propuesta sobre el motivo por el cual era necesaria una comercializaci\u00f3n de producto m\u00e1s coordinada para educar de manera efectiva a una base de clientes m\u00e1s amplia respecto a las novedades de ConMet. Ahora, como Gerente de Comercializaci\u00f3n de Producto, ella garantiza que cuando ConMet lanza un nuevo producto o servicio, las personas sepan qui\u00e9n es ConMet, qu\u00e9 representa, y por qu\u00e9 confiar en las entregas.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f1e0771\" data-id=\"3f1e0771\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c1d0135 elementor-widget elementor-widget-image\" data-id=\"4c1d0135\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"588\" src=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-sidebar-1024x753.jpg\" class=\"attachment-large size-large wp-image-3278\" alt=\"\" srcset=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-sidebar-1024x753.jpg 1024w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-sidebar-300x221.jpg 300w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-sidebar-768x564.jpg 768w, https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-sidebar.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5a18bf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a5a18bf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f0ca0b\" data-id=\"6f0ca0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-27cbbfd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27cbbfd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-979a3bb\" data-id=\"979a3bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1dc702 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"a1dc702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\u201cNos consideramos traductores, tomamos un concepto t\u00e9cnico complejo y cambiamos el enfoque hacia el valor que la tecnolog\u00eda aporta a un cliente.\u201d\t\t\t<\/p>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba8ea97 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"ba8ea97\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-887f9e1\" data-id=\"887f9e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63f356a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63f356a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ad7498\" data-id=\"2ad7498\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36c530f elementor-widget elementor-widget-heading\" data-id=\"36c530f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ansiosa por introducir ideas ingeniosas al mercado<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-445730b elementor-widget elementor-widget-text-editor\" data-id=\"445730b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El equipo de Sarah ha ajustado su enfoque para desarrollar planes de lanzamiento, posicionar productos de manera m\u00e1s minuiciosa, expresar la propuesta de valor de los productos, y transmitir c\u00f3mo aportar\u00e1 al valor general del producto de sus cliente \u2013 aumentando la seguridad, rentabilidad, y mayor sostenibilidad. Con su experiencia, Sarah puede desarrollar herramientas que permitan a su equipo mejorar el desempe\u00f1o, haciendo que la informaci\u00f3n sobre las nuevas tecnolog\u00edas sea m\u00e1s f\u00e1cil de comprender para los clientes.<\/p>\n<p>\u201cNuestros ingenieros son expertos muy valiosos en nuestra industria, nos ayudan a comprender un producto t\u00e9cnico o explicar el caso de uso detr\u00e1s del verdadero valor al cliente.\u201d Esto permite a su equipo de comercializaci\u00f3n enviar mensajes mediante el grupo de ventas, prepararlos para un mejor posicionamiento de producto, y perfeccionar el valor de la marca general de la empresa mediante mensajes coherentes.<\/p>\n<p>Quisiera replantear un poco esto. Ya que en realidad se trata de desarrollar herramientas que permitan a nuestros equipos de Ventas y Desarrollo Empresarial un desempe\u00f1o m\u00e1s excelente.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d57d65\" data-id=\"5d57d65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0404663 elementor-widget elementor-widget-heading\" data-id=\"0404663\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ver el futuro, ser el futuro.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7093805 elementor-widget elementor-widget-text-editor\" data-id=\"7093805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cLas flotas se han ido consolidando,\u201d Sarah indica. \u201cComo resultado, vemos m\u00e1s solidaridad con la forma en que las flotas se est\u00e1n acercanco a las nuevas tecnolog\u00edas.\u201d Trabajando en conjunto con Desarrollo Comercial, Gerentes de Producto, Ingenier\u00eda, y Ventas, Sarah espera impulsar este cambio mediante la comercializaci\u00f3n de innovaciones de productos directamente al usuario final para desarrollar mejores experiencias en los clientes con productos ConMet.<\/p>\n<p>Mientras ConMet presiona para avanzar en la expansi\u00f3n de la industria hacia las nuevas tecnolog\u00edas, los mensajes de comercializaci\u00f3n de Sarah se han ampliado para demostrar la forma en que estos productos y servicios preparan a los fabricantes de equipos originales y a las flotas para seguir siendo competitivos. Sarah resume su misi\u00f3n para los pr\u00f3ximos a\u00f1os, \u201cQueremos llevar la experiencia del cliente y el valor de la marca ConMet a niveles m\u00e1s altos.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49201a2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"49201a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e17634\" data-id=\"2e17634\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8bcc4f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8bcc4f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3b18bb3\" data-id=\"3b18bb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5f1f08 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"f5f1f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\u201cA\u00fan cuando uno cree que sabe algo, la industria est\u00e1 en constante cambio por eso es fundamental seguir aprendiendo.\u201d\t\t\t<\/p>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":4932,"template":"","class_list":["post-6599","career_profiles","type-career_profiles","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sarah Evans - Amsted Industries<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sarah Evans - Amsted Industries\" \/>\n<meta property=\"og:description\" content=\"ConMetGerente de Comercializaci\u00f3n de ProductoVancouver, Washington, Estados Unidos Talento para mantener la comunicaci\u00f3n con el cliente usando tecnolog\u00eda de punta Sarah pas\u00f3 de la comercializaci\u00f3n de equipos m\u00e9dicos a la industria de transporte comercial porque estaba fascinada por la velocidad en que los productos y servicios para veh\u00edculos adoptaban nuevas tecnolog\u00edas. Sab\u00eda que iba a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/\" \/>\n<meta property=\"og:site_name\" content=\"Amsted Industries\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-22T14:18:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-thumb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1279\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/profiles\\\/sarah-evans\\\/\",\"url\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/profiles\\\/sarah-evans\\\/\",\"name\":\"Sarah Evans - Amsted Industries\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/profiles\\\/sarah-evans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/profiles\\\/sarah-evans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amsted.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cm-sarah-thumb.jpg\",\"datePublished\":\"2022-08-12T03:54:17+00:00\",\"dateModified\":\"2022-09-22T14:18:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/profiles\\\/sarah-evans\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amsted.com\\\/es\\\/profiles\\\/sarah-evans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/profiles\\\/sarah-evans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amsted.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cm-sarah-thumb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amsted.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cm-sarah-thumb.jpg\",\"width\":800,\"height\":1279},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/profiles\\\/sarah-evans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sarah Evans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/\",\"name\":\"Amsted Industries\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amsted.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sarah Evans - Amsted Industries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/","og_locale":"es_ES","og_type":"article","og_title":"Sarah Evans - Amsted Industries","og_description":"ConMetGerente de Comercializaci\u00f3n de ProductoVancouver, Washington, Estados Unidos Talento para mantener la comunicaci\u00f3n con el cliente usando tecnolog\u00eda de punta Sarah pas\u00f3 de la comercializaci\u00f3n de equipos m\u00e9dicos a la industria de transporte comercial porque estaba fascinada por la velocidad en que los productos y servicios para veh\u00edculos adoptaban nuevas tecnolog\u00edas. Sab\u00eda que iba a [&hellip;]","og_url":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/","og_site_name":"Amsted Industries","article_modified_time":"2022-09-22T14:18:35+00:00","og_image":[{"width":800,"height":1279,"url":"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-thumb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/","url":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/","name":"Sarah Evans - Amsted Industries","isPartOf":{"@id":"https:\/\/www.amsted.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/#primaryimage"},"image":{"@id":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-thumb.jpg","datePublished":"2022-08-12T03:54:17+00:00","dateModified":"2022-09-22T14:18:35+00:00","breadcrumb":{"@id":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/#primaryimage","url":"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-thumb.jpg","contentUrl":"https:\/\/www.amsted.com\/wp-content\/uploads\/2022\/08\/cm-sarah-thumb.jpg","width":800,"height":1279},{"@type":"BreadcrumbList","@id":"https:\/\/www.amsted.com\/es\/profiles\/sarah-evans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.amsted.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sarah Evans"}]},{"@type":"WebSite","@id":"https:\/\/www.amsted.com\/es\/#website","url":"https:\/\/www.amsted.com\/es\/","name":"Amsted Industries","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amsted.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/career_profiles\/6599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/career_profiles"}],"about":[{"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/types\/career_profiles"}],"version-history":[{"count":1,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/career_profiles\/6599\/revisions"}],"predecessor-version":[{"id":6600,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/career_profiles\/6599\/revisions\/6600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/media\/4932"}],"wp:attachment":[{"href":"https:\/\/www.amsted.com\/es\/wp-json\/wp\/v2\/media?parent=6599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}